{"id":9702,"date":"2024-10-24T19:44:19","date_gmt":"2024-10-24T17:44:19","guid":{"rendered":"https:\/\/topskinews.com\/?p=9702"},"modified":"2026-05-17T07:41:11","modified_gmt":"2026-05-17T07:41:11","slug":"caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu","status":"publish","type":"post","link":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/","title":{"rendered":"Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Avec une pr\u00e9paration estivale r\u00e9ussie, Caitlin McFarlane se sent pr\u00eate \u00e0 attaquer la saison de ski alpin plus t\u00f4t que ce qu\u2019elle avait pr\u00e9vu. Ce samedi, elle prendra son premier d\u00e9part en g\u00e9ant sur la piste de S\u00f6lden, un \u00e9v\u00e9nement qu\u2019elle a longtemps admir\u00e9 de loin. Dans cette interview, elle partage ses r\u00e9flexions sur sa pr\u00e9paration, nous parle de ses disciplines de pr\u00e9dilection, de ses objectifs, et sa qu\u00eate de r\u00e9gularit\u00e9 sur le circuit international.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Quels enseignements as-tu tir\u00e9 de la saison derni\u00e8re&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u2019ai appris qu\u2019il fallait vivre dans le pr\u00e9sent. M\u00eame si je fais une bonne manche, il ne faut pas que je m\u2019emballe et penser aux cons\u00e9quences de ma deuxi\u00e8me. &nbsp;Je dois essayer de me concentrer sur chaque manche&nbsp;!<\/p>\n\n\n\n<figure class=\"wp-block-image alignwide size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"567\" src=\"https:\/\/testing.topskinews.com\/wp-content\/uploads\/2024\/10\/a24-jawg-pb-01-0817.jpg\" alt=\"\" class=\"wp-image-9704\" srcset=\"https:\/\/testing.topskinews.com\/wp-content\/uploads\/2024\/10\/a24-jawg-pb-01-0817.jpg 850w, https:\/\/testing.topskinews.com\/wp-content\/uploads\/2024\/10\/a24-jawg-pb-01-0817-300x200.jpg 300w, https:\/\/testing.topskinews.com\/wp-content\/uploads\/2024\/10\/a24-jawg-pb-01-0817-768x512.jpg 768w\" sizes=\"auto, (max-width: 850px) 100vw, 850px\" \/><figcaption class=\"wp-element-caption\"><strong>La meilleure performance de la derni\u00e8re saison, Caitlin Mcfarlane l&rsquo;a sign\u00e9 au g\u00e9ant de Jasna en janvier : 23e avec le dossard 68 !! &#8211; Photo copyright Agence Zoom\/Paul Brechu<\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Peux-tu nous parler de ta pr\u00e9paration estivale&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On a fait un tr\u00e8s bon \u00e9t\u00e9 avec un bon stage en Argentine. On a fait des s\u00e9lections \u00e0 Ushiaia car il n\u2019y a que trois places ici \u00e0 S\u00f6lden et on est plus que trois \u00e0 pr\u00e9tendre \u00eatre au d\u00e9part.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Que repr\u00e9sente S\u00f6lden pour toi\u00a0?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est une grosse course. Je l\u2019a regardais tous les ans avec ma famille donc cela fait un peu bizarre d\u2019\u00eatre l\u00e0. J\u2019ai super h\u00e2te d\u2019\u00eatre au d\u00e9part car c\u2019est une piste magnifique, un \u00e9norme \u00e9v\u00e9nement. Je suis l\u00e0 pour prendre de l\u2019exp\u00e9rience.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Samedi, tu prendras ton premier d\u00e9part en g\u00e9ant \u00e0 Solden. Est-ce que cette piste peut te convenir&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Je pense que oui car elle me plait. Je suis plut\u00f4t \u00e0 l\u2019aise la plupart du temps dans les parties raides. Et l\u00e0 il y en a une tr\u00e8s tr\u00e8s longue [sourire].<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Dans quelles disciplines vas-tu courir cette saison, et as-tu une pr\u00e9f\u00e9rence entre elles&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mon objectif, c\u2019est slalom et g\u00e9ant, et d\u2019essayer de performer dans les deux. Bizarrement, j\u2019ai l\u2019impression d\u2019\u00eatre moins stress\u00e9e en g\u00e9ant qu\u2019en slalom. Je ne sais pas pourquoi&nbsp;! Cela m\u2019est arriv\u00e9e en fin de saison et cet \u00e9t\u00e9 en Argentine sur des pistes un peu plus difficiles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais je ne peux pas vraiment dire que j\u2019ai une pr\u00e9f\u00e9rence entre slalom et g\u00e9ant.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A quoi peut ressembler une belle saison pour toi&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plus de r\u00e9gularit\u00e9, plus de d\u00e9parts et plus d\u2019arriv\u00e9es dans les 30 sur les deux manches. J\u2019ai aussi dans un coin de ma t\u00eate le r\u00eave des Championnats du monde de Saalbach. Je suis pr\u00eate \u00e0 me battre pour y aller&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec une pr\u00e9paration estivale r\u00e9ussie, Caitlin McFarlane se sent pr\u00eate \u00e0 attaquer la saison de ski alpin plus t\u00f4t que ce qu\u2019elle avait pr\u00e9vu. Ce samedi, elle prendra son premier d\u00e9part en g\u00e9ant sur la piste de S\u00f6lden, un \u00e9v\u00e9nement qu\u2019elle a longtemps admir\u00e9 de loin. Dans cette interview, elle partage ses r\u00e9flexions sur sa&#8230;<\/p>\n","protected":false},"author":1,"featured_media":9703,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[3],"tags":[],"class_list":["post-9702","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb. - Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb. - Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition\" \/>\n<meta property=\"og:description\" content=\"Avec une pr\u00e9paration estivale r\u00e9ussie, Caitlin McFarlane se sent pr\u00eate \u00e0 attaquer la saison de ski alpin plus t\u00f4t que ce qu\u2019elle avait pr\u00e9vu. Ce samedi, elle prendra son premier d\u00e9part en g\u00e9ant sur la piste de S\u00f6lden, un \u00e9v\u00e9nement qu\u2019elle a longtemps admir\u00e9 de loin. Dans cette interview, elle partage ses r\u00e9flexions sur sa...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/\" \/>\n<meta property=\"og:site_name\" content=\"Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-24T17:44:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-17T07:41:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/testing.topskinews.com\/wp-content\/uploads\/2024\/10\/IMG_9818.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1187\" \/>\n\t<meta property=\"og:image:height\" content=\"1055\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"topskinews_admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"topskinews_admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/\"},\"author\":{\"name\":\"topskinews_admin\",\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/#\\\/schema\\\/person\\\/48e629a406c020bc8dab9031fa57341d\"},\"headline\":\"Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb.\",\"datePublished\":\"2024-10-24T17:44:19+00:00\",\"dateModified\":\"2026-05-17T07:41:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/\"},\"wordCount\":531,\"publisher\":{\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/testing.topskinews.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_9818.jpg\",\"articleSection\":[\"Coupe du monde\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/\",\"url\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/\",\"name\":\"Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb. - Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/testing.topskinews.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_9818.jpg\",\"datePublished\":\"2024-10-24T17:44:19+00:00\",\"dateModified\":\"2026-05-17T07:41:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/testing.topskinews.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_9818.jpg\",\"contentUrl\":\"https:\\\/\\\/testing.topskinews.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/IMG_9818.jpg\",\"width\":1187,\"height\":1055},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/2024\\\/10\\\/24\\\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/testing.topskinews.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/#website\",\"url\":\"https:\\\/\\\/testing.topskinews.com\\\/\",\"name\":\"Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition\",\"description\":\"Si vous aimez le ski alpin vous \u00eates au bon endroit.\",\"publisher\":{\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/testing.topskinews.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/#organization\",\"name\":\"Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition\",\"url\":\"https:\\\/\\\/testing.topskinews.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/testing.topskinews.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-TOPSKINEWS_logo_transparent_500px.png\",\"contentUrl\":\"https:\\\/\\\/testing.topskinews.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-TOPSKINEWS_logo_transparent_500px.png\",\"width\":530,\"height\":330,\"caption\":\"Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition\"},\"image\":{\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/testing.topskinews.com\\\/#\\\/schema\\\/person\\\/48e629a406c020bc8dab9031fa57341d\",\"name\":\"topskinews_admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abeb38c2b8b696211eb41aca6e34d77b72f2b378bf689210c63a11165436c93a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abeb38c2b8b696211eb41aca6e34d77b72f2b378bf689210c63a11165436c93a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/abeb38c2b8b696211eb41aca6e34d77b72f2b378bf689210c63a11165436c93a?s=96&d=mm&r=g\",\"caption\":\"topskinews_admin\"},\"sameAs\":[\"http:\\\/\\\/testing.topskinews.com\"],\"url\":\"https:\\\/\\\/testing.topskinews.com\\\/index.php\\\/author\\\/topskinews_admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb. - Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb. - Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition","og_description":"Avec une pr\u00e9paration estivale r\u00e9ussie, Caitlin McFarlane se sent pr\u00eate \u00e0 attaquer la saison de ski alpin plus t\u00f4t que ce qu\u2019elle avait pr\u00e9vu. Ce samedi, elle prendra son premier d\u00e9part en g\u00e9ant sur la piste de S\u00f6lden, un \u00e9v\u00e9nement qu\u2019elle a longtemps admir\u00e9 de loin. Dans cette interview, elle partage ses r\u00e9flexions sur sa...","og_url":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/","og_site_name":"Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition","article_published_time":"2024-10-24T17:44:19+00:00","article_modified_time":"2026-05-17T07:41:11+00:00","og_image":[{"width":1187,"height":1055,"url":"https:\/\/testing.topskinews.com\/wp-content\/uploads\/2024\/10\/IMG_9818.jpg","type":"image\/jpeg"}],"author":"topskinews_admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"topskinews_admin","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/#article","isPartOf":{"@id":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/"},"author":{"name":"topskinews_admin","@id":"https:\/\/testing.topskinews.com\/#\/schema\/person\/48e629a406c020bc8dab9031fa57341d"},"headline":"Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb.","datePublished":"2024-10-24T17:44:19+00:00","dateModified":"2026-05-17T07:41:11+00:00","mainEntityOfPage":{"@id":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/"},"wordCount":531,"publisher":{"@id":"https:\/\/testing.topskinews.com\/#organization"},"image":{"@id":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/#primaryimage"},"thumbnailUrl":"https:\/\/testing.topskinews.com\/wp-content\/uploads\/2024\/10\/IMG_9818.jpg","articleSection":["Coupe du monde"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/","url":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/","name":"Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb. - Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition","isPartOf":{"@id":"https:\/\/testing.topskinews.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/#primaryimage"},"image":{"@id":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/#primaryimage"},"thumbnailUrl":"https:\/\/testing.topskinews.com\/wp-content\/uploads\/2024\/10\/IMG_9818.jpg","datePublished":"2024-10-24T17:44:19+00:00","dateModified":"2026-05-17T07:41:11+00:00","breadcrumb":{"@id":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/#primaryimage","url":"https:\/\/testing.topskinews.com\/wp-content\/uploads\/2024\/10\/IMG_9818.jpg","contentUrl":"https:\/\/testing.topskinews.com\/wp-content\/uploads\/2024\/10\/IMG_9818.jpg","width":1187,"height":1055},{"@type":"BreadcrumbList","@id":"https:\/\/testing.topskinews.com\/index.php\/2024\/10\/24\/caitlain-mcfarlane-je-suis-en-forme-pour-un-debut-de-saison-plus-tot-que-prevu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/testing.topskinews.com\/"},{"@type":"ListItem","position":2,"name":"Caitlin McFarlane\u00a0: \u00ab\u00a0Je suis en forme pour un d\u00e9but de saison plus t\u00f4t que pr\u00e9vu\u00a0\u00bb."}]},{"@type":"WebSite","@id":"https:\/\/testing.topskinews.com\/#website","url":"https:\/\/testing.topskinews.com\/","name":"Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition","description":"Si vous aimez le ski alpin vous \u00eates au bon endroit.","publisher":{"@id":"https:\/\/testing.topskinews.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/testing.topskinews.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/testing.topskinews.com\/#organization","name":"Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition","url":"https:\/\/testing.topskinews.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/testing.topskinews.com\/#\/schema\/logo\/image\/","url":"https:\/\/testing.topskinews.com\/wp-content\/uploads\/2026\/05\/cropped-TOPSKINEWS_logo_transparent_500px.png","contentUrl":"https:\/\/testing.topskinews.com\/wp-content\/uploads\/2026\/05\/cropped-TOPSKINEWS_logo_transparent_500px.png","width":530,"height":330,"caption":"Toute l&#039;actualit\u00e9 du ski alpin de comp\u00e9tition"},"image":{"@id":"https:\/\/testing.topskinews.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/testing.topskinews.com\/#\/schema\/person\/48e629a406c020bc8dab9031fa57341d","name":"topskinews_admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/abeb38c2b8b696211eb41aca6e34d77b72f2b378bf689210c63a11165436c93a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/abeb38c2b8b696211eb41aca6e34d77b72f2b378bf689210c63a11165436c93a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/abeb38c2b8b696211eb41aca6e34d77b72f2b378bf689210c63a11165436c93a?s=96&d=mm&r=g","caption":"topskinews_admin"},"sameAs":["http:\/\/testing.topskinews.com"],"url":"https:\/\/testing.topskinews.com\/index.php\/author\/topskinews_admin\/"}]}},"_links":{"self":[{"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/posts\/9702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/comments?post=9702"}],"version-history":[{"count":1,"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/posts\/9702\/revisions"}],"predecessor-version":[{"id":13868,"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/posts\/9702\/revisions\/13868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/media\/9703"}],"wp:attachment":[{"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/media?parent=9702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/categories?post=9702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/testing.topskinews.com\/index.php\/wp-json\/wp\/v2\/tags?post=9702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}